{"id":10172,"date":"2026-05-12T16:33:54","date_gmt":"2026-05-12T19:33:54","guid":{"rendered":"https:\/\/radioclubedeinhapim.com.br\/?p=10172"},"modified":"2026-05-12T16:34:22","modified_gmt":"2026-05-12T19:34:22","slug":"febraban-alerta-para-golpe-do-falso-emprego","status":"publish","type":"post","link":"https:\/\/radioclubedeinhapim.com.br\/index.php\/2026\/05\/12\/febraban-alerta-para-golpe-do-falso-emprego\/","title":{"rendered":"Febraban alerta para golpe do falso emprego"},"content":{"rendered":"\n<p>A Federa\u00e7\u00e3o Brasileira de Bancos (Febraban) divulgou comunicado nesta ter\u00e7a-feira (12) alertando para o golpe do falso emprego. Segundo a entidade, criminosos assediam pessoas que est\u00e3o procurando trabalho e oferecem o que parece ser \u201cuma vaga imperd\u00edvel\u201d. A oferta enganosa \u00e9 isca para capturar dados de candidatos.<\/p>\n\n\n\n<p>De acordo com a Febraban, criminosos se passam por falsos recrutadores e tamb\u00e9m como integrantes de falsas ag\u00eancias de emprego enviando mensagens por WhatsApp, e-mail ou em redes sociais.<\/p>\n\n\n\n<p>&#8220;Assim, obt\u00eam fotos das v\u00edtimas, imagens de documentos, informa\u00e7\u00f5es banc\u00e1rias e assinaturas digitais&#8221;, alerta.<\/p>\n\n\n\n<p>Al\u00e9m de dados, os golpistas podem pedir dinheiro para pagamento de taxa de inscri\u00e7\u00e3o, realiza\u00e7\u00e3o de falsos exames m\u00e9dicos ou pagamento de curso preparat\u00f3rio para a vaga que n\u00e3o existe.<\/p>\n\n\n\n<p>Os riscos, al\u00e9m de perder dinheiro imediatamente com essas despesas fict\u00edcias, s\u00e3o as v\u00edtimas terem sua imagem usada em autentica\u00e7\u00f5es biom\u00e9tricas e, junto com documentos informa\u00e7\u00f5es banc\u00e1rias, os criminosos levantarem financiamentos em nome das pessoas que ca\u00edram no golpe.<\/p>\n\n\n\n<p>No golpe do falso emprego, os criminosos cometem estelionato, que \u00e9 a vantagem il\u00edcita para si ou para outra pessoa em preju\u00edzo da v\u00edtima, furto mediante fraude e apropria\u00e7\u00e3o ind\u00e9bita. Os tr\u00eas delitos est\u00e3o previstos no C\u00f3digo Penal.<\/p>\n\n\n\n<p>No comunicado, a Febraban faz cinco recomenda\u00e7\u00f5es para n\u00e3o cair no golpe do falso emprego:<\/p>\n\n\n\n<p>\u25aa\ufe0fDesconfie de processos seletivos simplificados e da oferta de sal\u00e1rios muito acima da m\u00e9dia do mercado para as fun\u00e7\u00f5es descritas.<br>\u25aa\ufe0fAntes de abrir links indicados em mensagens, verifique diretamente no site ou nas redes sociais da empresa se a vaga existe de fato.<br>\u25aa\ufe0fConfirme se o recrutador \u00e9 aut\u00eantico e possui conex\u00f5es reais. <\/p>\n\n\n\n<p>\u25aa\ufe0fSe receber mensagens por e-mail verifique se o endere\u00e7o \u00e9 corporativo.<br>\u25aa\ufe0fN\u00e3o envie foto de documento, dados banc\u00e1rios ou assinatura digital sem ter certeza da idoneidade da empresa.<br>\u25aa\ufe0fN\u00e3o efetue qualquer tipo de pagamento zero: taxa de inscri\u00e7\u00e3o, exames ou cursos pr\u00e9-contrata\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"has-small-font-size\">Ag\u00eancia Brasil<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Federa\u00e7\u00e3o Brasileira de Bancos (Febraban) divulgou comunicado nesta ter\u00e7a-feira (12) alertando para o golpe do falso emprego. Segundo a entidade, criminosos assediam pessoas que est\u00e3o procurando trabalho e oferecem o que parece ser \u201cuma vaga imperd\u00edvel\u201d. A oferta enganosa \u00e9 isca para capturar dados de candidatos. De acordo com a Febraban, criminosos se passam [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":10173,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-10172","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"wpmagazine_modules_lite_featured_media_urls":{"thumbnail":["https:\/\/radioclubedeinhapim.com.br\/wp-content\/uploads\/2026\/05\/1-2-150x150.jpg",150,150,true],"cvmm-medium":["https:\/\/radioclubedeinhapim.com.br\/wp-content\/uploads\/2026\/05\/1-2-300x300.jpg",300,300,true],"cvmm-medium-plus":["https:\/\/radioclubedeinhapim.com.br\/wp-content\/uploads\/2026\/05\/1-2-305x207.jpg",305,207,true],"cvmm-portrait":["https:\/\/radioclubedeinhapim.com.br\/wp-content\/uploads\/2026\/05\/1-2-400x600.jpg",400,600,true],"cvmm-medium-square":["https:\/\/radioclubedeinhapim.com.br\/wp-content\/uploads\/2026\/05\/1-2-600x600.jpg",600,600,true],"cvmm-large":["https:\/\/radioclubedeinhapim.com.br\/wp-content\/uploads\/2026\/05\/1-2-1024x1024.jpg",1024,1024,true],"cvmm-small":["https:\/\/radioclubedeinhapim.com.br\/wp-content\/uploads\/2026\/05\/1-2-130x95.jpg",130,95,true],"full":["https:\/\/radioclubedeinhapim.com.br\/wp-content\/uploads\/2026\/05\/1-2.jpg",1080,1080,false]},"categories_names":{"5":{"name":"Not\u00edcias","link":"https:\/\/radioclubedeinhapim.com.br\/index.php\/category\/noticias\/"}},"tags_names":[],"comments_number":"0","_links":{"self":[{"href":"https:\/\/radioclubedeinhapim.com.br\/index.php\/wp-json\/wp\/v2\/posts\/10172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radioclubedeinhapim.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radioclubedeinhapim.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radioclubedeinhapim.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radioclubedeinhapim.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=10172"}],"version-history":[{"count":3,"href":"https:\/\/radioclubedeinhapim.com.br\/index.php\/wp-json\/wp\/v2\/posts\/10172\/revisions"}],"predecessor-version":[{"id":10176,"href":"https:\/\/radioclubedeinhapim.com.br\/index.php\/wp-json\/wp\/v2\/posts\/10172\/revisions\/10176"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radioclubedeinhapim.com.br\/index.php\/wp-json\/wp\/v2\/media\/10173"}],"wp:attachment":[{"href":"https:\/\/radioclubedeinhapim.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=10172"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radioclubedeinhapim.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=10172"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radioclubedeinhapim.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=10172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}