{"id":1290,"date":"2024-08-14T11:09:53","date_gmt":"2024-08-14T14:09:53","guid":{"rendered":"https:\/\/radioclubedeinhapim.com.br\/?p=1290"},"modified":"2024-08-14T11:13:12","modified_gmt":"2024-08-14T14:13:12","slug":"vazamento-de-gas-em-usina-de-asfalto-causa-interdicao-da-br-116-em-governador-valadares","status":"publish","type":"post","link":"https:\/\/radioclubedeinhapim.com.br\/index.php\/2024\/08\/14\/vazamento-de-gas-em-usina-de-asfalto-causa-interdicao-da-br-116-em-governador-valadares\/","title":{"rendered":"Vazamento de g\u00e1s em usina de asfalto causa interdi\u00e7\u00e3o da BR-116 em Governador Valadares"},"content":{"rendered":"\n<p>Um susto na tarde da \u00faltima segunda-feira mobilizou os Bombeiros Militares de Governador Valadares. Um vazamento de g\u00e1s liquefeito de petr\u00f3leo (GLP) em uma usina de asfalto localizada \u00e0s margens da BR-116, sentido Alpercata, exigiu a interdi\u00e7\u00e3o da rodovia por um per\u00edodo.<\/p>\n\n\n\n<p>O incidente foi registrado por volta das 14h. Ao chegarem ao local, os bombeiros constataram que quatro tanques estacion\u00e1rios estavam presentes, sendo que um deles, com aproximadamente 1.000 quilos de g\u00e1s, apresentava um vazamento em uma das v\u00e1lvulas.<\/p>\n\n\n\n<p>Diante da situa\u00e7\u00e3o, uma equipe da empresa respons\u00e1vel pelo produto foi acionada e se deslocou de Coronel Fabriciano para tentar conter o vazamento. No entanto, os t\u00e9cnicos n\u00e3o conseguiram realizar a troca da pe\u00e7a com \u00eaxito.<\/p>\n\n\n\n<p>Para garantir a seguran\u00e7a de todos, a BR-116 precisou ser interditada enquanto os bombeiros trabalhavam para controlar a situa\u00e7\u00e3o. A equipe utilizou cerca de 10 mil litros de \u00e1gua em um processo t\u00e9cnico conhecido como rebatimento, que consiste em diluir o g\u00e1s no ar at\u00e9 que o tanque ficasse vazio. N\u00e3o houve feridos durante o incidente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um susto na tarde da \u00faltima segunda-feira mobilizou os Bombeiros Militares de Governador Valadares. Um vazamento de g\u00e1s liquefeito de petr\u00f3leo (GLP) em uma usina de asfalto localizada \u00e0s margens da BR-116, sentido Alpercata, exigiu a interdi\u00e7\u00e3o da rodovia por um per\u00edodo. O incidente foi registrado por volta das 14h. Ao chegarem ao local, os [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1291,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,1],"tags":[],"class_list":["post-1290","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-uncategorized"],"wpmagazine_modules_lite_featured_media_urls":{"thumbnail":["https:\/\/radioclubedeinhapim.com.br\/wp-content\/uploads\/2024\/08\/2-150x150.jpg",150,150,true],"cvmm-medium":["https:\/\/radioclubedeinhapim.com.br\/wp-content\/uploads\/2024\/08\/2-300x300.jpg",300,300,true],"cvmm-medium-plus":["https:\/\/radioclubedeinhapim.com.br\/wp-content\/uploads\/2024\/08\/2-305x207.jpg",305,207,true],"cvmm-portrait":["https:\/\/radioclubedeinhapim.com.br\/wp-content\/uploads\/2024\/08\/2-400x600.jpg",400,600,true],"cvmm-medium-square":["https:\/\/radioclubedeinhapim.com.br\/wp-content\/uploads\/2024\/08\/2-600x600.jpg",600,600,true],"cvmm-large":["https:\/\/radioclubedeinhapim.com.br\/wp-content\/uploads\/2024\/08\/2-1024x1024.jpg",1024,1024,true],"cvmm-small":["https:\/\/radioclubedeinhapim.com.br\/wp-content\/uploads\/2024\/08\/2-130x95.jpg",130,95,true],"full":["https:\/\/radioclubedeinhapim.com.br\/wp-content\/uploads\/2024\/08\/2.jpg",1080,1080,false]},"categories_names":{"5":{"name":"Not\u00edcias","link":"https:\/\/radioclubedeinhapim.com.br\/index.php\/category\/noticias\/"},"1":{"name":"Uncategorized","link":"https:\/\/radioclubedeinhapim.com.br\/index.php\/category\/uncategorized\/"}},"tags_names":[],"comments_number":"0","_links":{"self":[{"href":"https:\/\/radioclubedeinhapim.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radioclubedeinhapim.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radioclubedeinhapim.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radioclubedeinhapim.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radioclubedeinhapim.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1290"}],"version-history":[{"count":1,"href":"https:\/\/radioclubedeinhapim.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1290\/revisions"}],"predecessor-version":[{"id":1292,"href":"https:\/\/radioclubedeinhapim.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1290\/revisions\/1292"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radioclubedeinhapim.com.br\/index.php\/wp-json\/wp\/v2\/media\/1291"}],"wp:attachment":[{"href":"https:\/\/radioclubedeinhapim.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1290"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radioclubedeinhapim.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=1290"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radioclubedeinhapim.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=1290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}