{"id":9650,"date":"2026-03-25T09:57:16","date_gmt":"2026-03-25T12:57:16","guid":{"rendered":"https:\/\/radioclubedeinhapim.com.br\/?p=9650"},"modified":"2026-03-25T09:57:16","modified_gmt":"2026-03-25T12:57:16","slug":"mp-recomenda-medidas-rigorosas-para-coibir-aumentos-abusivos-nos-precos-dos-combustiveis","status":"publish","type":"post","link":"https:\/\/radioclubedeinhapim.com.br\/index.php\/2026\/03\/25\/mp-recomenda-medidas-rigorosas-para-coibir-aumentos-abusivos-nos-precos-dos-combustiveis\/","title":{"rendered":"MP recomenda medidas rigorosas para coibir aumentos abusivos nos pre\u00e7os dos combust\u00edveis"},"content":{"rendered":"\n<p>O Minist\u00e9rio P\u00fablico de Minas Gerais, por meio da 14\u00aa Promotoria de Justi\u00e7a de Defesa do Consumidor, expediu recomenda\u00e7\u00e3o aos postos revendedores de combust\u00edveis do estado e ao Sindicato do Com\u00e9rcio Varejista de Derivados de Petr\u00f3leo de Minas Gerais para ado\u00e7\u00e3o imediata de medidas de conformidade na precifica\u00e7\u00e3o e no dever de informa\u00e7\u00e3o ao consumidor.<\/p>\n\n\n\n<p>O documento orienta que os fornecedores se abstenham de promover aumentos de pre\u00e7os sem justa causa, ou seja, sem respaldo em eleva\u00e7\u00e3o efetiva e comprovada dos custos de aquisi\u00e7\u00e3o junto \u00e0s distribuidoras. Tamb\u00e9m ficam vedados reajustes baseados apenas em expectativas de mercado ou an\u00fancios futuros, especialmente quando aplicados a estoques adquiridos por valores inferiores.<\/p>\n\n\n\n<p>A iniciativa refor\u00e7a entendimento do C\u00f3digo de Defesa do Consumidor, que considera abusiva a eleva\u00e7\u00e3o de pre\u00e7os sem justificativa. A recomenda\u00e7\u00e3o tamb\u00e9m segue diretrizes da Secretaria Nacional do Consumidor, que exige que reajustes sejam baseados em dados objetivos e verific\u00e1veis, como notas fiscais.<\/p>\n\n\n\n<p>Al\u00e9m da precifica\u00e7\u00e3o, o texto destaca a obriga\u00e7\u00e3o de transpar\u00eancia. Os postos devem manter, em local vis\u00edvel, informa\u00e7\u00f5es sobre benef\u00edcios tribut\u00e1rios incidentes, conforme decreto federal, e identificar nas bombas a distribuidora respons\u00e1vel pelo combust\u00edvel.<\/p>\n\n\n\n<p>Outro ponto \u00e9 o dever de manter documenta\u00e7\u00e3o organizada e dispon\u00edvel para fiscaliza\u00e7\u00e3o, incluindo notas fiscais, cupons e registros de movimenta\u00e7\u00e3o. Os estabelecimentos tamb\u00e9m devem atender prontamente \u00e0s requisi\u00e7\u00f5es do Procon-MPMG e das Promotorias.<\/p>\n\n\n\n<p>A medida est\u00e1 alinhada \u00e0 estrat\u00e9gia de fiscaliza\u00e7\u00e3o baseada em intelig\u00eancia de dados do Procon-MPMG, que monitora pre\u00e7os e cruza informa\u00e7\u00f5es em todo o estado.<\/p>\n\n\n\n<p>O Minaspetro deve informar em at\u00e9 cinco dias as a\u00e7\u00f5es adotadas para divulgar a recomenda\u00e7\u00e3o. Em caso de descumprimento, o MPMG poder\u00e1 adotar medidas administrativas e judiciais, incluindo multas e outras san\u00e7\u00f5es.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Minist\u00e9rio P\u00fablico de Minas Gerais, por meio da 14\u00aa Promotoria de Justi\u00e7a de Defesa do Consumidor, expediu recomenda\u00e7\u00e3o aos postos revendedores de combust\u00edveis do estado e ao Sindicato do Com\u00e9rcio Varejista de Derivados de Petr\u00f3leo de Minas Gerais para ado\u00e7\u00e3o imediata de medidas de conformidade na precifica\u00e7\u00e3o e no dever de informa\u00e7\u00e3o ao consumidor. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9651,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-9650","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"wpmagazine_modules_lite_featured_media_urls":{"thumbnail":["https:\/\/radioclubedeinhapim.com.br\/wp-content\/uploads\/2026\/03\/Copia-de-Inserir-um-subtitulo-2-2-150x150.jpg",150,150,true],"cvmm-medium":["https:\/\/radioclubedeinhapim.com.br\/wp-content\/uploads\/2026\/03\/Copia-de-Inserir-um-subtitulo-2-2-300x300.jpg",300,300,true],"cvmm-medium-plus":["https:\/\/radioclubedeinhapim.com.br\/wp-content\/uploads\/2026\/03\/Copia-de-Inserir-um-subtitulo-2-2-305x207.jpg",305,207,true],"cvmm-portrait":["https:\/\/radioclubedeinhapim.com.br\/wp-content\/uploads\/2026\/03\/Copia-de-Inserir-um-subtitulo-2-2-400x600.jpg",400,600,true],"cvmm-medium-square":["https:\/\/radioclubedeinhapim.com.br\/wp-content\/uploads\/2026\/03\/Copia-de-Inserir-um-subtitulo-2-2-600x600.jpg",600,600,true],"cvmm-large":["https:\/\/radioclubedeinhapim.com.br\/wp-content\/uploads\/2026\/03\/Copia-de-Inserir-um-subtitulo-2-2-1024x1024.jpg",1024,1024,true],"cvmm-small":["https:\/\/radioclubedeinhapim.com.br\/wp-content\/uploads\/2026\/03\/Copia-de-Inserir-um-subtitulo-2-2-130x95.jpg",130,95,true],"full":["https:\/\/radioclubedeinhapim.com.br\/wp-content\/uploads\/2026\/03\/Copia-de-Inserir-um-subtitulo-2-2.jpg",1080,1080,false]},"categories_names":{"5":{"name":"Not\u00edcias","link":"https:\/\/radioclubedeinhapim.com.br\/index.php\/category\/noticias\/"}},"tags_names":[],"comments_number":"0","_links":{"self":[{"href":"https:\/\/radioclubedeinhapim.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9650","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radioclubedeinhapim.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radioclubedeinhapim.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radioclubedeinhapim.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radioclubedeinhapim.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=9650"}],"version-history":[{"count":1,"href":"https:\/\/radioclubedeinhapim.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9650\/revisions"}],"predecessor-version":[{"id":9652,"href":"https:\/\/radioclubedeinhapim.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9650\/revisions\/9652"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radioclubedeinhapim.com.br\/index.php\/wp-json\/wp\/v2\/media\/9651"}],"wp:attachment":[{"href":"https:\/\/radioclubedeinhapim.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=9650"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radioclubedeinhapim.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=9650"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radioclubedeinhapim.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=9650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}